{"id":57,"count":5,"description":"","link":"https:\/\/hikingrhodes.com\/de\/category\/tagliche-wanderung\/lindos-bereich\/","name":"Lindos Bereich","slug":"lindos-bereich","taxonomy":"category","parent":61,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lindos Bereich Archivi - Hiking Rhodes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hikingrhodes.com\/de\/category\/tagliche-wanderung\/lindos-bereich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lindos Bereich Archivi - Hiking Rhodes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hikingrhodes.com\/de\/category\/tagliche-wanderung\/lindos-bereich\/\" \/>\n<meta property=\"og:site_name\" content=\"Hiking Rhodes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hikingrhodes.com\\\/de\\\/category\\\/tagliche-wanderung\\\/lindos-bereich\\\/\",\"url\":\"https:\\\/\\\/hikingrhodes.com\\\/de\\\/category\\\/tagliche-wanderung\\\/lindos-bereich\\\/\",\"name\":\"Lindos Bereich Archivi - Hiking Rhodes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hikingrhodes.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hikingrhodes.com\\\/de\\\/category\\\/tagliche-wanderung\\\/lindos-bereich\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hikingrhodes.com\\\/de\\\/category\\\/tagliche-wanderung\\\/lindos-bereich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hikingrhodes.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00c4GLICHE WANDERUNG\",\"item\":\"https:\\\/\\\/hikingrhodes.com\\\/de\\\/category\\\/tagliche-wanderung\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lindos Bereich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hikingrhodes.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/hikingrhodes.com\\\/de\\\/\",\"name\":\"Hiking Rhodes\",\"description\":\"Hiking e trekking nella meravigliosa isola di Rodi\",\"publisher\":{\"@id\":\"https:\\\/\\\/hikingrhodes.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hikingrhodes.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hikingrhodes.com\\\/de\\\/#organization\",\"name\":\"RodiTrekking\",\"url\":\"https:\\\/\\\/hikingrhodes.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hikingrhodes.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hikingrhodes.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/rodi-trekking_sticky-logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/hikingrhodes.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/rodi-trekking_sticky-logo-retina.png\",\"width\":400,\"height\":123,\"caption\":\"RodiTrekking\"},\"image\":{\"@id\":\"https:\\\/\\\/hikingrhodes.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lindos Bereich Archivi - Hiking Rhodes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hikingrhodes.com\/de\/category\/tagliche-wanderung\/lindos-bereich\/","og_locale":"de_DE","og_type":"article","og_title":"Lindos Bereich Archivi - Hiking Rhodes","og_url":"https:\/\/hikingrhodes.com\/de\/category\/tagliche-wanderung\/lindos-bereich\/","og_site_name":"Hiking Rhodes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hikingrhodes.com\/de\/category\/tagliche-wanderung\/lindos-bereich\/","url":"https:\/\/hikingrhodes.com\/de\/category\/tagliche-wanderung\/lindos-bereich\/","name":"Lindos Bereich Archivi - Hiking Rhodes","isPartOf":{"@id":"https:\/\/hikingrhodes.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/hikingrhodes.com\/de\/category\/tagliche-wanderung\/lindos-bereich\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/hikingrhodes.com\/de\/category\/tagliche-wanderung\/lindos-bereich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hikingrhodes.com\/de\/"},{"@type":"ListItem","position":2,"name":"T\u00c4GLICHE WANDERUNG","item":"https:\/\/hikingrhodes.com\/de\/category\/tagliche-wanderung\/"},{"@type":"ListItem","position":3,"name":"Lindos Bereich"}]},{"@type":"WebSite","@id":"https:\/\/hikingrhodes.com\/de\/#website","url":"https:\/\/hikingrhodes.com\/de\/","name":"Hiking Rhodes","description":"Hiking e trekking nella meravigliosa isola di Rodi","publisher":{"@id":"https:\/\/hikingrhodes.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hikingrhodes.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hikingrhodes.com\/de\/#organization","name":"RodiTrekking","url":"https:\/\/hikingrhodes.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hikingrhodes.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/hikingrhodes.com\/wp-content\/uploads\/2019\/06\/rodi-trekking_sticky-logo-retina.png","contentUrl":"https:\/\/hikingrhodes.com\/wp-content\/uploads\/2019\/06\/rodi-trekking_sticky-logo-retina.png","width":400,"height":123,"caption":"RodiTrekking"},"image":{"@id":"https:\/\/hikingrhodes.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hikingrhodes.com\/de\/wp-json\/wp\/v2\/categories\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hikingrhodes.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/hikingrhodes.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/hikingrhodes.com\/de\/wp-json\/wp\/v2\/categories\/61"}],"wp:post_type":[{"href":"https:\/\/hikingrhodes.com\/de\/wp-json\/wp\/v2\/posts?categories=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}